{"id":828,"date":"2017-04-18T17:11:00","date_gmt":"2017-04-18T15:11:00","guid":{"rendered":"https:\/\/dbo-network.org\/dbo\/?p=828"},"modified":"2022-11-18T17:11:54","modified_gmt":"2022-11-18T16:11:54","slug":"neuer-auszubildender-in-der-schreinerei","status":"publish","type":"post","link":"https:\/\/dbo-network.org\/dbo\/2017\/04\/18\/neuer-auszubildender-in-der-schreinerei\/","title":{"rendered":"Neuer Auszubildender in der Schreinerei"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Hallo, mein Name ist Modou Mbaye. Ich bin Auszubildender in der Schreinerei und lerne gerade die Zinkung von Brettern f\u00fcr neue K\u00fcchenm\u00f6bel.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo, mein Name ist Modou Mbaye. Ich bin Auszubildender in der Schreinerei und lerne gerade die Zinkung von Brettern f\u00fcr neue K\u00fcchenm\u00f6bel.<\/p>\n","protected":false},"author":1,"featured_media":829,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tischlerei"],"_links":{"self":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":1,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"predecessor-version":[{"id":830,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/828\/revisions\/830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}