{"id":1515,"date":"2017-01-03T01:28:00","date_gmt":"2017-01-03T00:28:00","guid":{"rendered":"https:\/\/dbo-network.org\/dbo\/?p=1515"},"modified":"2022-11-22T01:29:06","modified_gmt":"2022-11-22T00:29:06","slug":"baeckerei-neubau","status":"publish","type":"post","link":"https:\/\/dbo-network.org\/dbo\/2017\/01\/03\/baeckerei-neubau\/","title":{"rendered":"B\u00e4ckerei Neubau"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das wir ein neues Projekt haben, dar\u00fcber haben wir ja schon berichtet. Das Equipment, samt Ofen haben wir von der Peter Backwaren OHG in Essen gespendet bekommen und es steht bereits in Gambia. Nebenbei haben wir angefangen, das Geb\u00e4ude drumherum, n\u00e4mlich Lagerr\u00e4ume im Restaurant &#8222;Blue Kitchen&#8220;, auszubauen. Hier zeigen wir nun den Baufortschritt samt Denkfehlern&#8230;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"294\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330591.jpg\" alt=\"\" class=\"wp-image-1516\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330591.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330591-300x173.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Eine ordentliche Absperrung zeigt, hier entsteht was Neues<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330616.jpg\" alt=\"\" class=\"wp-image-1517\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330616.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330616-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Der erste Spatenstich f\u00fcr die Geb\u00e4udeerweiterung ist getan<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330601.jpg\" alt=\"\" class=\"wp-image-1518\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330601.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330601-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Innen wird eine T\u00fcr zu den hinteren Lagerr\u00e4umen eingebaut und die Fensterl\u00f6cher kommen in die Wand<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330611.jpg\" alt=\"\" class=\"wp-image-1519\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330611.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330611-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Die Fliesen werden schon verlegt und neue Metallfenster sind eingebaut,<br>bald soll ja die B\u00e4ckerei er\u00f6ffnen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330606.jpg\" alt=\"\" class=\"wp-image-1520\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330606.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330606-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Dann kam der Klaus Peter (rechts) aus Essen, der uns die B\u00e4ckerei gesponsert hat, w\u00e4hrend der Rallye nach Gambia und nat\u00fcrlich ins Blue Kitchen und hat erkl\u00e4rt, so geht das nicht, das wird ja viel zu heiss in dem kleinen Raum.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330596.jpg\" alt=\"\" class=\"wp-image-1521\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330596.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330596-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">OK, dann also richtig und raus mit der Wand<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330626.jpg\" alt=\"\" class=\"wp-image-1522\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330626.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330626-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">So, sieht das dann aus. Man kann bis zur blauen K\u00fcche (daher der Name &#8222;Blue Kitchen&#8220;) durchgucken<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330621.jpg\" alt=\"\" class=\"wp-image-1523\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330621.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330621-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Damit die Hitze auch nach oben abziehen kann, wird das Dach abgetragen und aufgestockt. Nach vorn wird die Wand rausgebrochen.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"510\" height=\"383\" src=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330636.jpg\" alt=\"\" class=\"wp-image-1524\" srcset=\"https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330636.jpg 510w, https:\/\/dbo-network.org\/dbo\/wp-content\/uploads\/sites\/2\/2022\/11\/44330636-300x225.jpg 300w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><figcaption class=\"wp-element-caption\">Nun kann das Dach mit dem typischen Dachblech neu gedeckt werden<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Das wir ein neues Projekt haben, dar\u00fcber haben wir ja schon berichtet. Das Equipment, samt Ofen haben wir von der Peter Backwaren OHG in Essen gespendet bekommen und es steht bereits in Gambia. Nebenbei haben wir angefangen, das Geb\u00e4ude drumherum,&#8230; <a class=\"more-link\" href=\"https:\/\/dbo-network.org\/dbo\/2017\/01\/03\/baeckerei-neubau\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1525,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baeckerei"],"_links":{"self":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/1515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/comments?post=1515"}],"version-history":[{"count":1,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/1515\/revisions"}],"predecessor-version":[{"id":1526,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/posts\/1515\/revisions\/1526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/media\/1525"}],"wp:attachment":[{"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/media?parent=1515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/categories?post=1515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dbo-network.org\/dbo\/wp-json\/wp\/v2\/tags?post=1515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}